{"id":16704,"date":"2020-03-05T23:15:35","date_gmt":"2020-03-05T23:15:35","guid":{"rendered":"https:\/\/s5c.72e.mywebsitetransfer.com\/?p=16704"},"modified":"2025-11-30T10:11:19","modified_gmt":"2025-11-30T15:11:19","slug":"purepower-technologies-adds-23-new-light-duty-turbo-skus-to-expanding-aftermarket-lineup","status":"publish","type":"post","link":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-adds-23-new-light-duty-turbo-skus-to-expanding-aftermarket-lineup\/","title":{"rendered":"PurePower Technologies aggiunge 23 nuove SKU di Turbo Light-Duty all'espansione della linea Aftermarket"},"content":{"rendered":"<p><strong>COLUMBIA, S.C. -<\/strong> 5 marzo 2020 - <a href=\"https:\/\/purepowertechnologies.com\/\" target=\"_blank\" rel=\"noopener\">Tecnologie PurePower<\/a> (PPT), un leader nell'ingegneria e nella rigenerazione di iniettori di carburante diesel e turbocompressori, ha aggiunto 23 nuovi numeri di parte di qualit\u00e0 superiore per i turbocompressori leggeri per l'aftermarket.<\/p>\n<p>Dal suo pi\u00f9 recente lancio nel marzo 2019, PPT si \u00e8 concentrata sull'introduzione di una linea ampliata di turbo che copre il mercato dei pick-up diesel light-duty. Queste nuove offerte aumentano i prodotti turbo dell'azienda attraverso marche e modelli ad alto volume che offrono potenza, affidabilit\u00e0 ed efficienza per i motori diesel leggeri che soddisfano o superano le specifiche OE.<\/p>\n<p>PurePower offre ora un totale di 30 numeri di parte di turbo, compresa la recente aggiunta del 2007-2012 Dodge 6.7L alla linea. La prossima uscita con i turbo Dodge 6.7L 2013-2018 sar\u00e0 in aprile, seguita da altre due uscite nel corso dell'anno per completare la linea di turbo leggeri dell'azienda.<\/p>\n<p>Tutti <a href=\"https:\/\/www.purepowertechnologies.com\/product-categories\/turbos\">Turbo PPT<\/a> sono sottoposti a rigorosi test di fine linea come un assemblaggio completo, assicurando le migliori prestazioni del settore e la massima efficienza in uscita, mentre soddisfano i pi\u00f9 severi standard del sistema di qualit\u00e0 automobilistico.<\/p>\n<p>\"Questi turbocompressori diesel di alta precisione continuano la nostra strategia di crescita a lungo termine di offrire solo i turbocompressori di pi\u00f9 alta qualit\u00e0 all'aftermarket, sfruttando la nostra eredit\u00e0 OE e i processi di rigenerazione migliori della categoria\", ha dichiarato Greg Butler, amministratore delegato di PurePower Technologies. \"Siamo entusiasti di offrire una linea di prodotti ampliata di turbocompressori nuovi e rigenerati che sono posizionati per essere la scelta ottimale per l'investimento del cliente nei motori diesel\".<\/p>\n<p>Per saperne di pi\u00f9 sulla nuova linea di turbocompressori diesel di PurePower o su come diventare un partner di distribuzione, contattate <a href=\"mailto:sales@purepowertech.com\">sales@purepowertech.com<\/a>.<\/p>\n<p><strong>Informazioni su PurePower Technologies:<\/strong><\/p>\n<p>PurePower Technologies, Inc., una societ\u00e0 di Stanadyne LLC, \u00e8 leader nella progettazione e rigenerazione di iniettori di carburante diesel e turbocompressori per gli OEM e l'aftermarket. Con sede a Columbia, S.C., l'azienda \u00e8 un'autorit\u00e0 per tutti i sistemi di precisione di carburante, gestione dell'aria e post-trattamento per motori diesel leggeri, medi e pesanti, avendo prodotto pi\u00f9 di 30 milioni di iniettori di carburante diesel di precisione dal 1999. PurePower offre un portafoglio completo di capacit\u00e0 di progettazione, ingegneria, produzione e rigenerazione che permette all'azienda di raggiungere livelli di qualit\u00e0 e precisione che superano quelli dell'industria. Per maggiori informazioni, visitate <a href=\"http:\/\/purepowertechnologies.com\/\">purepowertechnologies.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>COLUMBIA, S.C. \u2013 March 5, 2020 \u2013 PurePower Technologies (PPT), a leader in the engineering and remanufacturing of diesel fuel injectors and turbochargers, has added 23 premium-quality, new light-duty turbo part numbers for the aftermarket. Since its most recent launch in March 2019, PPT has focused on introducing an expanded line of turbos that covers&hellip;<\/p>","protected":false},"author":11,"featured_media":16716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-16704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","category-7","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup - Stanadyne<\/title>\n<meta name=\"description\" content=\"PurePower Technologies (PPT), has added 23 premium-quality, new light-duty turbo part numbers for the aftermarket.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup - Stanadyne\" \/>\n<meta property=\"og:description\" content=\"PurePower Technologies (PPT), has added 23 premium-quality, new light-duty turbo part numbers for the aftermarket.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/\" \/>\n<meta property=\"og:site_name\" content=\"Stanadyne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Stanadyne\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T23:15:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-30T15:11:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stanadyne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@StanadyneGlobal\" \/>\n<meta name=\"twitter:site\" content=\"@StanadyneGlobal\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stanadyne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/\"},\"author\":{\"name\":\"Stanadyne\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/person\\\/1f5f2aac1064faab8f78d3791fd50794\"},\"headline\":\"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup\",\"datePublished\":\"2020-03-05T23:15:35+00:00\",\"dateModified\":\"2025-11-30T15:11:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-Turbos-630x630.jpg\",\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/\",\"name\":\"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup - Stanadyne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-Turbos-630x630.jpg\",\"datePublished\":\"2020-03-05T23:15:35+00:00\",\"dateModified\":\"2025-11-30T15:11:19+00:00\",\"description\":\"PurePower Technologies (PPT), has added 23 premium-quality, new light-duty turbo part numbers for the aftermarket.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-Turbos-630x630.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-Turbos-630x630.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"On & off highway markets\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/it\\\/2020\\\/03\\\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stanadyne.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#website\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/\",\"name\":\"Stanadyne\",\"description\":\"Accelerating Engine Innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stanadyne.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\",\"name\":\"Stanadyne\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/amalgamations-main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/amalgamations-main.jpg\",\"width\":711,\"height\":328,\"caption\":\"Stanadyne\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Stanadyne\",\"https:\\\/\\\/x.com\\\/StanadyneGlobal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/53299?trk=tyah&amp;amp;amp;amp;trkInfo=tarId:1415624915381,tas:stanadyne,idx:2-1-4\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/person\\\/1f5f2aac1064faab8f78d3791fd50794\",\"name\":\"Stanadyne\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PurePower Technologies aggiunge 23 nuove SKU di Turbo Light-Duty all'espansione della linea Aftermarket - Stanadyne","description":"PurePower Technologies (PPT) ha aggiunto 23 nuovi numeri di pezzi di ricambio di qualit\u00e0 superiore per i turbocompressori leggeri per l'aftermarket.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/","og_locale":"it_IT","og_type":"article","og_title":"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup - Stanadyne","og_description":"PurePower Technologies (PPT), has added 23 premium-quality, new light-duty turbo part numbers for the aftermarket.","og_url":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/","og_site_name":"Stanadyne","article_publisher":"https:\/\/www.facebook.com\/Stanadyne","article_published_time":"2020-03-05T23:15:35+00:00","article_modified_time":"2025-11-30T15:11:19+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg","type":"image\/jpeg"}],"author":"Stanadyne","twitter_card":"summary_large_image","twitter_creator":"@StanadyneGlobal","twitter_site":"@StanadyneGlobal","twitter_misc":{"Scritto da":"Stanadyne","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#article","isPartOf":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/"},"author":{"name":"Stanadyne","@id":"https:\/\/www.stanadyne.com\/#\/schema\/person\/1f5f2aac1064faab8f78d3791fd50794"},"headline":"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup","datePublished":"2020-03-05T23:15:35+00:00","dateModified":"2025-11-30T15:11:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/"},"wordCount":356,"publisher":{"@id":"https:\/\/www.stanadyne.com\/#organization"},"image":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg","articleSection":["Press Releases"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/","url":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/","name":"PurePower Technologies aggiunge 23 nuove SKU di Turbo Light-Duty all'espansione della linea Aftermarket - Stanadyne","isPartOf":{"@id":"https:\/\/www.stanadyne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#primaryimage"},"image":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg","datePublished":"2020-03-05T23:15:35+00:00","dateModified":"2025-11-30T15:11:19+00:00","description":"PurePower Technologies (PPT) ha aggiunto 23 nuovi numeri di pezzi di ricambio di qualit\u00e0 superiore per i turbocompressori leggeri per l'aftermarket.","breadcrumb":{"@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#primaryimage","url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg","contentUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/2-Turbos-630x630.jpg","width":1080,"height":1080,"caption":"On & off highway markets"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stanadyne.com\/it\/2020\/03\/purepower-technologies-aggiunge-23-nuovi-turbo-skus-per-impieghi-leggeri-allespansione-della-linea-aftermarket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stanadyne.com\/"},{"@type":"ListItem","position":2,"name":"PurePower Technologies Adds 23 New Light-Duty Turbo SKUs to Expanding Aftermarket Lineup"}]},{"@type":"WebSite","@id":"https:\/\/www.stanadyne.com\/#website","url":"https:\/\/www.stanadyne.com\/","name":"Stanadyne","description":"Accelerazione dell'innovazione dei motori","publisher":{"@id":"https:\/\/www.stanadyne.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stanadyne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.stanadyne.com\/#organization","name":"Stanadyne","url":"https:\/\/www.stanadyne.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.stanadyne.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2016\/07\/amalgamations-main.jpg","contentUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2016\/07\/amalgamations-main.jpg","width":711,"height":328,"caption":"Stanadyne"},"image":{"@id":"https:\/\/www.stanadyne.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Stanadyne","https:\/\/x.com\/StanadyneGlobal","https:\/\/www.linkedin.com\/company\/53299?trk=tyah&amp;amp;amp;amp;trkInfo=tarId:1415624915381,tas:stanadyne,idx:2-1-4"]},{"@type":"Person","@id":"https:\/\/www.stanadyne.com\/#\/schema\/person\/1f5f2aac1064faab8f78d3791fd50794","name":"Stanadyne"}]}},"_links":{"self":[{"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/posts\/16704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/comments?post=16704"}],"version-history":[{"count":3,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/posts\/16704\/revisions"}],"predecessor-version":[{"id":17090,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/posts\/16704\/revisions\/17090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/media\/16716"}],"wp:attachment":[{"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/media?parent=16704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/categories?post=16704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stanadyne.com\/it\/wp-json\/wp\/v2\/tags?post=16704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}