{"id":16267,"date":"2018-05-30T14:43:44","date_gmt":"2018-05-30T14:43:44","guid":{"rendered":"https:\/\/s5c.72e.mywebsitetransfer.com\/?p=16267"},"modified":"2025-11-30T10:11:19","modified_gmt":"2025-11-30T15:11:19","slug":"stanadyne-hires-seasoned-leader-expand-business-americas","status":"publish","type":"post","link":"https:\/\/www.stanadyne.com\/es\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/","title":{"rendered":"Stanadyne contrata a un experimentado l\u00edder para ampliar su negocio en Am\u00e9rica"},"content":{"rendered":"<h4>David Zimmerman se une a Stanadyne como Director General de las Am\u00e9ricas, aportando un conjunto de habilidades vers\u00e1tiles en ingenier\u00eda y ventas de componentes de automoci\u00f3n<\/h4>\n<p><strong>Windsor, Conn. (30 de mayo de 2018)<\/strong> - Stanadyne, una compa\u00f1\u00eda global de sistemas de inyecci\u00f3n de combustible con sede en Windsor, Connecticut, ha anunciado hoy la contrataci\u00f3n de David Zimmerman como Director General de las Am\u00e9ricas. Con 30 a\u00f1os de experiencia en el sector de la automoci\u00f3n, Zimmerman aplicar\u00e1 su experiencia en gesti\u00f3n de ventas y operaciones para ampliar el negocio de Stanadyne en Am\u00e9rica del Norte y del Sur.<\/p>\n<div id=\"attachment_16271\" style=\"width: 224px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-16271\" class=\"wp-image-16271 size-medium\" src=\"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY-214x300.jpg 214w, https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY-768x1075.jpg 768w, https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY-731x1024.jpg 731w, https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY-450x630.jpg 450w, https:\/\/www.stanadyne.com\/wp-content\/uploads\/2018\/05\/Zimmerman.Dave_GRAY.jpg 771w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><p id=\"caption-attachment-16271\" class=\"wp-caption-text\">Dave Zimmerman, Director General de las Am\u00e9ricas<\/p><\/div>\n<p>Antes de trabajar en Stanadyne, Zimmerman fue Director Global de Ventas en Continental Automotive, donde representaba a seis unidades de negocio con puntos de contacto de fabricaci\u00f3n en seis continentes.   Zimmerman se centr\u00f3 en el desarrollo de nuevos mercados de trenes motrices para satisfacer la r\u00e1pida evoluci\u00f3n de las demandas de emisiones y electrificaci\u00f3n, al tiempo que aumentaba el negocio existente, lo que dio como resultado aproximadamente $2B en ventas incrementales.<\/p>\n<p>Zimmerman estructurar\u00e1 el negocio de Stanadyne en Am\u00e9rica y desarrollar\u00e1 estrategias de crecimiento en los mercados de ventas de equipos originales (OE) y de posventa de Stanadyne. Adem\u00e1s, Zimmerman continuar\u00e1 impulsando la excelencia operativa en toda la organizaci\u00f3n de Stanadyne en Am\u00e9rica, posicionando el negocio para el crecimiento de los resultados.<\/p>\n<p>\"Los productos de sistemas de combustible de Stanadyne est\u00e1n ganando cada vez m\u00e1s adeptos en todo el mundo. Expandir nuestro alcance a nuevos mercados es una estrategia clave para asegurar una competitividad continua\", dice David Galuska, Director General de Stanadyne. \"David tiene un historial probado de \u00e9xito en el crecimiento del negocio de la automoci\u00f3n y de las cuentas de ventas a nivel mundial, y espero verle ampliar nuestro alcance en las Am\u00e9ricas.\"<\/p>\n<p>Comenz\u00f3 su carrera en Lear Corporation como ingeniero de pruebas, Zimmerman supervis\u00f3 el desarrollo del sistema de asientos del monovolumen Windstar de Ford Motor Company, hasta ampliar sus horizontes como ingeniero residente en BorgWarner. Fue aqu\u00ed donde pas\u00f3 a desempe\u00f1ar un papel de ventas, convirti\u00e9ndose finalmente en el principal gestor de cuentas para los sistemas de combustible y la cadena cinem\u00e1tica.<\/p>\n<p>A lo largo de su carrera, Zimmerman ha liderado la expansi\u00f3n de los productos de tren motriz en mercados nuevos y existentes, garantizando el cumplimiento de las normativas sobre emisiones y permaneciendo en sinton\u00eda con la voz del cliente, para ofrecer productos de alto rendimiento para una experiencia de conducci\u00f3n superior.<\/p>\n<p>\"Stanadyne es una empresa innovadora que est\u00e1 transformando las expectativas de la industria sobre las capacidades de los equipos de inyecci\u00f3n de combustible\", dice Zimmerman. \"Estoy deseando introducirme en nuevos mercados y construir el negocio en las Am\u00e9ricas. Stanadyne est\u00e1 en movimiento y estoy emocionado de ser parte de su futuro.\"<\/p>\n<p>Zimmerman es licenciado en ingenier\u00eda mec\u00e1nica por la Western Michigan University.<\/p>","protected":false},"excerpt":{"rendered":"<p>David Zimmerman Joins Stanadyne as Managing Director of the Americas, Brings Versatile Skillset in Automotive Components Engineering and Sales Windsor, Conn. (May 30, 2018) &#8211;\u00a0 Stanadyne, a global fuel injection systems company based in Windsor, Connecticut, today announced the hiring of David Zimmerman as its Managing Director of the Americas. A 30-year veteran in the&hellip;<\/p>","protected":false},"author":11,"featured_media":16721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[38,36,39,37,16],"class_list":["post-16267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","tag-americas","tag-global","tag-managing-director-of-the-americas","tag-sales","tag-stanadyne","category-7","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stanadyne Hires Seasoned Leader to Expand Business in the Americas - Stanadyne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stanadyne.com\/es\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stanadyne Hires Seasoned Leader to Expand Business in the Americas - Stanadyne\" \/>\n<meta property=\"og:description\" content=\"David Zimmerman Joins Stanadyne as Managing Director of the Americas, Brings Versatile Skillset in Automotive Components Engineering and Sales Windsor, Conn. (May 30, 2018) &#8211;\u00a0 Stanadyne, a global fuel injection systems company based in Windsor, Connecticut, today announced the hiring of David Zimmerman as its Managing Director of the Americas. A 30-year veteran in the&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stanadyne.com\/es\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/\" \/>\n<meta property=\"og:site_name\" content=\"Stanadyne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Stanadyne\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-30T14:43:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-30T15:11:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"549\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stanadyne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@StanadyneGlobal\" \/>\n<meta name=\"twitter:site\" content=\"@StanadyneGlobal\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stanadyne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/\"},\"author\":{\"name\":\"Stanadyne\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/person\\\/1f5f2aac1064faab8f78d3791fd50794\"},\"headline\":\"Stanadyne Hires Seasoned Leader to Expand Business in the Americas\",\"datePublished\":\"2018-05-30T14:43:44+00:00\",\"dateModified\":\"2025-11-30T15:11:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/\"},\"wordCount\":403,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/7-Headshot-David-Zimmerman.jpg\",\"keywords\":[\"Americas\",\"Global\",\"Managing Director of the Americas\",\"sales\",\"Stanadyne\"],\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/\",\"name\":\"Stanadyne Hires Seasoned Leader to Expand Business in the Americas - Stanadyne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/7-Headshot-David-Zimmerman.jpg\",\"datePublished\":\"2018-05-30T14:43:44+00:00\",\"dateModified\":\"2025-11-30T15:11:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/7-Headshot-David-Zimmerman.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/7-Headshot-David-Zimmerman.jpg\",\"width\":549,\"height\":549,\"caption\":\"David Zimmerman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/2018\\\/05\\\/stanadyne-hires-seasoned-leader-expand-business-americas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stanadyne.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stanadyne Hires Seasoned Leader to Expand Business in the Americas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#website\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/\",\"name\":\"Stanadyne\",\"description\":\"Accelerating Engine Innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stanadyne.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#organization\",\"name\":\"Stanadyne\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/amalgamations-main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stanadyne.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/amalgamations-main.jpg\",\"width\":711,\"height\":328,\"caption\":\"Stanadyne\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Stanadyne\",\"https:\\\/\\\/x.com\\\/StanadyneGlobal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/53299?trk=tyah&amp;amp;amp;amp;trkInfo=tarId:1415624915381,tas:stanadyne,idx:2-1-4\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stanadyne.com\\\/#\\\/schema\\\/person\\\/1f5f2aac1064faab8f78d3791fd50794\",\"name\":\"Stanadyne\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stanadyne contrata a un experimentado l\u00edder para ampliar su negocio en Am\u00e9rica - Stanadyne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stanadyne.com\/es\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/","og_locale":"es_ES","og_type":"article","og_title":"Stanadyne Hires Seasoned Leader to Expand Business in the Americas - Stanadyne","og_description":"David Zimmerman Joins Stanadyne as Managing Director of the Americas, Brings Versatile Skillset in Automotive Components Engineering and Sales Windsor, Conn. (May 30, 2018) &#8211;\u00a0 Stanadyne, a global fuel injection systems company based in Windsor, Connecticut, today announced the hiring of David Zimmerman as its Managing Director of the Americas. A 30-year veteran in the&hellip;","og_url":"https:\/\/www.stanadyne.com\/es\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/","og_site_name":"Stanadyne","article_publisher":"https:\/\/www.facebook.com\/Stanadyne","article_published_time":"2018-05-30T14:43:44+00:00","article_modified_time":"2025-11-30T15:11:19+00:00","og_image":[{"width":549,"height":549,"url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg","type":"image\/jpeg"}],"author":"Stanadyne","twitter_card":"summary_large_image","twitter_creator":"@StanadyneGlobal","twitter_site":"@StanadyneGlobal","twitter_misc":{"Escrito por":"Stanadyne","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#article","isPartOf":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/"},"author":{"name":"Stanadyne","@id":"https:\/\/www.stanadyne.com\/#\/schema\/person\/1f5f2aac1064faab8f78d3791fd50794"},"headline":"Stanadyne Hires Seasoned Leader to Expand Business in the Americas","datePublished":"2018-05-30T14:43:44+00:00","dateModified":"2025-11-30T15:11:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/"},"wordCount":403,"publisher":{"@id":"https:\/\/www.stanadyne.com\/#organization"},"image":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg","keywords":["Americas","Global","Managing Director of the Americas","sales","Stanadyne"],"articleSection":["Press Releases"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/","url":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/","name":"Stanadyne contrata a un experimentado l\u00edder para ampliar su negocio en Am\u00e9rica - Stanadyne","isPartOf":{"@id":"https:\/\/www.stanadyne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#primaryimage"},"image":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg","datePublished":"2018-05-30T14:43:44+00:00","dateModified":"2025-11-30T15:11:19+00:00","breadcrumb":{"@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#primaryimage","url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg","contentUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2020\/03\/7-Headshot-David-Zimmerman.jpg","width":549,"height":549,"caption":"David Zimmerman"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stanadyne.com\/2018\/05\/stanadyne-hires-seasoned-leader-expand-business-americas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stanadyne.com\/"},{"@type":"ListItem","position":2,"name":"Stanadyne Hires Seasoned Leader to Expand Business in the Americas"}]},{"@type":"WebSite","@id":"https:\/\/www.stanadyne.com\/#website","url":"https:\/\/www.stanadyne.com\/","name":"Stanadyne","description":"Acelerar la innovaci\u00f3n en motores","publisher":{"@id":"https:\/\/www.stanadyne.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stanadyne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.stanadyne.com\/#organization","name":"Stanadyne","url":"https:\/\/www.stanadyne.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stanadyne.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2016\/07\/amalgamations-main.jpg","contentUrl":"https:\/\/www.stanadyne.com\/wp-content\/uploads\/2016\/07\/amalgamations-main.jpg","width":711,"height":328,"caption":"Stanadyne"},"image":{"@id":"https:\/\/www.stanadyne.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Stanadyne","https:\/\/x.com\/StanadyneGlobal","https:\/\/www.linkedin.com\/company\/53299?trk=tyah&amp;amp;amp;amp;trkInfo=tarId:1415624915381,tas:stanadyne,idx:2-1-4"]},{"@type":"Person","@id":"https:\/\/www.stanadyne.com\/#\/schema\/person\/1f5f2aac1064faab8f78d3791fd50794","name":"Stanadyne"}]}},"_links":{"self":[{"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/posts\/16267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/comments?post=16267"}],"version-history":[{"count":7,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/posts\/16267\/revisions"}],"predecessor-version":[{"id":41671,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/posts\/16267\/revisions\/41671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/media\/16721"}],"wp:attachment":[{"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/media?parent=16267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/categories?post=16267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stanadyne.com\/es\/wp-json\/wp\/v2\/tags?post=16267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}